{"id":3462,"date":"2021-10-12T17:33:56","date_gmt":"2021-10-12T15:33:56","guid":{"rendered":"https:\/\/sartori-ambiente.com\/referenze\/pantelleria-isola-green-in-un-anno\/"},"modified":"2021-11-18T18:48:58","modified_gmt":"2021-11-18T17:48:58","slug":"pantelleria-isla-green-en-un-ano","status":"publish","type":"referenze","link":"https:\/\/sartori-ambiente.com\/es\/referencias\/pantelleria-isla-green-en-un-ano\/","title":{"rendered":"Pantelleria, isla green en un a\u00f1o"},"content":{"rendered":"<h3>Situaci\u00f3n inicial<\/h3>\n<p>En 2014, Pantelleria produjo aproximadamente 4.500 toneladas de residuos, lo que equivale a una producci\u00f3n de 547 kg\/a\u00f1o\/habitante, de los cuales m\u00e1s del 30% estaba representado por la fracci\u00f3n org\u00e1nica. El coste del transporte de los residuos por mar super\u00f3 los 650.000 euros.<\/p>\n<p><strong>La recogida selectiva por carretera se situ\u00f3 en el 6%<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<h3>Objetivos<\/h3>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Configurar un nuevo servicio de recogida<\/strong> con una importante reducci\u00f3n de los residuos totales<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><strong>Control<\/strong> en tempo real del sistema<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><strong>Contenci\u00f3n de los costes<\/strong> del servicio<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\"><strong>Mejor calidad de vida<\/strong> <\/span>para los residentes y los visitantes<\/li>\n<\/ul>\n<p>Pantelleria se ha convertido en una isla \u201cGreen\u201d avanzando paso a paso. El servicio se activ\u00f3 gradualmente, comenzando en el casco antiguo de Pantelleria y en algunas comarcas vecinas a principios de enero de 2015, para concluir con las \u00faltimas zonas en octubre del mismo a\u00f1o.<\/p>\n<p>&nbsp;<\/p>\n<h3>Soluciones<\/h3>\n<ul>\n<li><b>Recogida puerta a puerta.<\/b> <span style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Se distribuyeron contenedores de <strong>10<\/strong> y <strong>23 litros<\/strong> a todos los ciudadanos para la recogida de la fracci\u00f3n org\u00e1nica y contenedores apilables de <strong>30\/40 litros <\/strong>para las fracciones de vidrio\/latas, papel, envases de pl\u00e1stico y resto (fracci\u00f3n indiferenciada)<\/span><\/span><\/li>\n<li>Los contenedores apilables de la serie <strong>UrbaPLUS<\/strong> son la herramienta ideal para los sistemas de recogida puerta a puerta; f\u00e1ciles de usar incluso apilados, ofrecen unas soluciones ergon\u00f3micas para el usuario que tiene que manipular o colocar el contenedor en el hogar, as\u00ed como para el operario de recogida que tiene que realizar numerosas operaciones de vaciado en cada turno de recogida<\/li>\n<li>Todos los contenedores est\u00e1n equipados con <strong>Tags RFID UHF<\/strong> para permitir el seguimiento instant\u00e1neo del vaciado de cualquier fracci\u00f3n de residuos que sea expuesta por cada usuario individual<\/li>\n<li>Los kits tambi\u00e9n se entregaron puerta a puerta, lo que permiti\u00f3 georreferenciar la ubicaci\u00f3n de cada contenedor y, por lo tanto, de cada usuario.<\/li>\n<li><strong>Instrumentaci\u00f3n para la detecci\u00f3n precisa de las operaciones de vaciado.<\/strong> El vaciado de los contenedores se detecta a trav\u00e9s del sistema de lectura RFID montado en los veh\u00edculos de recogida. El sistema elegido es el modelo <strong>Arco40EVO<\/strong>, desarrollado para garantizar la m\u00e1xima fiabilidad de la detecci\u00f3n con los m\u00ednimos costes de instalaci\u00f3n y gesti\u00f3n. <strong>Arco40EVO<\/strong> detecta autom\u00e1ticamente las operaciones de vaciado que efectivamente se han realizado, enviando la informaci\u00f3n en tiempo real al servidor junto con las coordenadas geogr\u00e1ficas, lo que supone un control total del funcionamiento de los veh\u00edculos de recogida<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h3>Resultados<\/h3>\n<p><strong>El<\/strong> <strong>porcentaje de recogida selectiva de residuos ha ido aumentando constantemente<\/strong>, pasando de alrededor del 6% en el mes de enero a m\u00e1s del 60% en diciembre, con la activaci\u00f3n del servicio en todo el territorio del municipio.<\/p>\n<p>Hay que tener en cuenta que las peculiaridades tur\u00edsticas de la isla provocan unos picos de producci\u00f3n de residuos en verano.<\/p>\n","protected":false},"featured_media":3021,"parent":0,"template":"","class_list":["post-3462","referenze","type-referenze","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pantelleria, isla green en un a\u00f1o | Sartori Ambiente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sartori-ambiente.com\/es\/referencias\/pantelleria-isla-green-en-un-ano\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pantelleria, isla green en un a\u00f1o | Sartori Ambiente\" \/>\n<meta property=\"og:description\" content=\"Situaci\u00f3n inicial En 2014, Pantelleria produjo aproximadamente 4.500 toneladas de residuos, lo que equivale a una producci\u00f3n de 547 kg\/a\u00f1o\/habitante, de los cuales m\u00e1s del 30% estaba representado por la fracci\u00f3n org\u00e1nica. El coste del transporte de los residuos por mar super\u00f3 los 650.000 euros. La recogida selectiva por carretera se situ\u00f3 en el 6%. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sartori-ambiente.com\/es\/referencias\/pantelleria-isla-green-en-un-ano\/\" \/>\n<meta property=\"og:site_name\" content=\"Sartori Ambiente\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-18T17:48:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sartori-ambiente.com\/wp-content\/uploads\/2021\/10\/Senza-titolo-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"690\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sartori-ambiente.com\\\/es\\\/referencias\\\/pantelleria-isla-green-en-un-ano\\\/\",\"url\":\"https:\\\/\\\/sartori-ambiente.com\\\/es\\\/referencias\\\/pantelleria-isla-green-en-un-ano\\\/\",\"name\":\"Pantelleria, isla green en un a\u00f1o | Sartori Ambiente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sartori-ambiente.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sartori-ambiente.com\\\/es\\\/referencias\\\/pantelleria-isla-green-en-un-ano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sartori-ambiente.com\\\/es\\\/referencias\\\/pantelleria-isla-green-en-un-ano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sartori-ambiente.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Pantelleria-1-800x600-1-1.jpg\",\"datePublished\":\"2021-10-12T15:33:56+00:00\",\"dateModified\":\"2021-11-18T17:48:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sartori-ambiente.com\\\/es\\\/referencias\\\/pantelleria-isla-green-en-un-ano\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sartori-ambiente.com\\\/es\\\/referencias\\\/pantelleria-isla-green-en-un-ano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/sartori-ambiente.com\\\/es\\\/referencias\\\/pantelleria-isla-green-en-un-ano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sartori-ambiente.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Pantelleria-1-800x600-1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/sartori-ambiente.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Pantelleria-1-800x600-1-1.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sartori-ambiente.com\\\/es\\\/referencias\\\/pantelleria-isla-green-en-un-ano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Referencias\",\"item\":\"https:\\\/\\\/sartori-ambiente.com\\\/es\\\/referencias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pantelleria, isla green en un a\u00f1o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sartori-ambiente.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/sartori-ambiente.com\\\/es\\\/\",\"name\":\"Sartori Ambiente\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/sartori-ambiente.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sartori-ambiente.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sartori-ambiente.com\\\/es\\\/#organization\",\"name\":\"Sartori Ambiente\",\"url\":\"https:\\\/\\\/sartori-ambiente.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/sartori-ambiente.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sartori-ambiente.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Sartori_Ambiente_logo.svg\",\"contentUrl\":\"https:\\\/\\\/sartori-ambiente.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Sartori_Ambiente_logo.svg\",\"width\":1,\"height\":1,\"caption\":\"Sartori Ambiente\"},\"image\":{\"@id\":\"https:\\\/\\\/sartori-ambiente.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pantelleria, isla green en un a\u00f1o | Sartori Ambiente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sartori-ambiente.com\/es\/referencias\/pantelleria-isla-green-en-un-ano\/","og_locale":"es_ES","og_type":"article","og_title":"Pantelleria, isla green en un a\u00f1o | Sartori Ambiente","og_description":"Situaci\u00f3n inicial En 2014, Pantelleria produjo aproximadamente 4.500 toneladas de residuos, lo que equivale a una producci\u00f3n de 547 kg\/a\u00f1o\/habitante, de los cuales m\u00e1s del 30% estaba representado por la fracci\u00f3n org\u00e1nica. El coste del transporte de los residuos por mar super\u00f3 los 650.000 euros. La recogida selectiva por carretera se situ\u00f3 en el 6%. [&hellip;]","og_url":"https:\/\/sartori-ambiente.com\/es\/referencias\/pantelleria-isla-green-en-un-ano\/","og_site_name":"Sartori Ambiente","article_modified_time":"2021-11-18T17:48:58+00:00","og_image":[{"width":690,"height":600,"url":"https:\/\/sartori-ambiente.com\/wp-content\/uploads\/2021\/10\/Senza-titolo-1-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sartori-ambiente.com\/es\/referencias\/pantelleria-isla-green-en-un-ano\/","url":"https:\/\/sartori-ambiente.com\/es\/referencias\/pantelleria-isla-green-en-un-ano\/","name":"Pantelleria, isla green en un a\u00f1o | Sartori Ambiente","isPartOf":{"@id":"https:\/\/sartori-ambiente.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sartori-ambiente.com\/es\/referencias\/pantelleria-isla-green-en-un-ano\/#primaryimage"},"image":{"@id":"https:\/\/sartori-ambiente.com\/es\/referencias\/pantelleria-isla-green-en-un-ano\/#primaryimage"},"thumbnailUrl":"https:\/\/sartori-ambiente.com\/wp-content\/uploads\/2021\/10\/Pantelleria-1-800x600-1-1.jpg","datePublished":"2021-10-12T15:33:56+00:00","dateModified":"2021-11-18T17:48:58+00:00","breadcrumb":{"@id":"https:\/\/sartori-ambiente.com\/es\/referencias\/pantelleria-isla-green-en-un-ano\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sartori-ambiente.com\/es\/referencias\/pantelleria-isla-green-en-un-ano\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sartori-ambiente.com\/es\/referencias\/pantelleria-isla-green-en-un-ano\/#primaryimage","url":"https:\/\/sartori-ambiente.com\/wp-content\/uploads\/2021\/10\/Pantelleria-1-800x600-1-1.jpg","contentUrl":"https:\/\/sartori-ambiente.com\/wp-content\/uploads\/2021\/10\/Pantelleria-1-800x600-1-1.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/sartori-ambiente.com\/es\/referencias\/pantelleria-isla-green-en-un-ano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Referencias","item":"https:\/\/sartori-ambiente.com\/es\/referencias\/"},{"@type":"ListItem","position":2,"name":"Pantelleria, isla green en un a\u00f1o"}]},{"@type":"WebSite","@id":"https:\/\/sartori-ambiente.com\/es\/#website","url":"https:\/\/sartori-ambiente.com\/es\/","name":"Sartori Ambiente","description":"","publisher":{"@id":"https:\/\/sartori-ambiente.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sartori-ambiente.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sartori-ambiente.com\/es\/#organization","name":"Sartori Ambiente","url":"https:\/\/sartori-ambiente.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sartori-ambiente.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/sartori-ambiente.com\/wp-content\/uploads\/2021\/09\/Sartori_Ambiente_logo.svg","contentUrl":"https:\/\/sartori-ambiente.com\/wp-content\/uploads\/2021\/09\/Sartori_Ambiente_logo.svg","width":1,"height":1,"caption":"Sartori Ambiente"},"image":{"@id":"https:\/\/sartori-ambiente.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/sartori-ambiente.com\/es\/wp-json\/wp\/v2\/referenze\/3462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sartori-ambiente.com\/es\/wp-json\/wp\/v2\/referenze"}],"about":[{"href":"https:\/\/sartori-ambiente.com\/es\/wp-json\/wp\/v2\/types\/referenze"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sartori-ambiente.com\/es\/wp-json\/wp\/v2\/media\/3021"}],"wp:attachment":[{"href":"https:\/\/sartori-ambiente.com\/es\/wp-json\/wp\/v2\/media?parent=3462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}