{"id":3463,"date":"2021-10-12T17:58:41","date_gmt":"2021-10-12T15:58:41","guid":{"rendered":"https:\/\/sartori-ambiente.com\/referenze\/la-differenziata-obiettivo-comune-in-valle\/"},"modified":"2021-11-18T17:40:37","modified_gmt":"2021-11-18T16:40:37","slug":"la-collective-selective-lobjectif-commun-de-cette-vallee","status":"publish","type":"referenze","link":"https:\/\/sartori-ambiente.com\/fr\/references\/la-collective-selective-lobjectif-commun-de-cette-vallee\/","title":{"rendered":"La collective s\u00e9lective: l&rsquo;objectif commun de cette vall\u00e9e"},"content":{"rendered":"<h3>\u00c9tat initial<\/h3>\n<ul>\n<li>Les chiffres de la collecte s\u00e9lective de 2017, publi\u00e9s par l&rsquo;Observatoire provincial des d\u00e9chets, avant que la fili\u00e8re ne soit confi\u00e9e \u00e0 la soci\u00e9t\u00e9 Sae sp\u00e9cialement fond\u00e9e par la communaut\u00e9 de montagne, indiquaient un taux de collecte s\u00e9lective des d\u00e9chets de 50\u00a0%.<\/li>\n<li>Les difficult\u00e9s de la population \u00e0 apprendre \u00e0 trier correctement tous les d\u00e9chets.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h3>Les objectifs<\/h3>\n<ul>\n<li>Mettre en \u0153uvre un syst\u00e8me plus performant, moins co\u00fbteux et plus respectueux de l&rsquo;environnement.<\/li>\n<li><strong>Impliquer et sensibiliser la population \u00e0 la collecte s\u00e9lective des d\u00e9chets.<\/strong><strong>Mettre en place une tarification incitative.<\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h3>Les solutions<\/h3>\n<p>Le <strong>syst\u00e8me de collecte en porte-\u00e0-porte <\/strong>a \u00e9t\u00e9 choisi pour 75\u00a0% de la population de la communaut\u00e9 de montagne. Les autres 25\u00a0% utilisent un <strong>syst\u00e8me mixte<\/strong>: collecte \u00e0 domicile pour papier-carton, emballages plastiques-m\u00e9talliques et verre, et collecte dans l&rsquo;espace public en points d&rsquo;apport contr\u00f4l\u00e9 pour les d\u00e9chets organiques et non recyclables.<\/p>\n<p><strong>Sartori Ambiente<\/strong> a contribu\u00e9 \u00e0 la r\u00e9alisation de ces deux syst\u00e8mes en proposant diff\u00e9rentes solutions:<\/p>\n<ul>\n<li>des <strong>strat\u00e9gies et des \u00e9quipements de collecte sp\u00e9cifiques pour chaque commune<\/strong>:\n<ul>\n<li>des conteneurs \u00e0 puce RFID d&rsquo;identification univoque fournis aux usagers<\/li>\n<li>des conteneurs roulants<\/li>\n<li>des points d&rsquo;apport dans l&rsquo;espace public<\/li>\n<\/ul>\n<\/li>\n<li>l&rsquo;installation de 30 bornes ArcoPOINT pour la collecte des textiles sanitaires. Ces bornes sont munies d&rsquo;un syst\u00e8me d&rsquo;identification des usagers qui doivent introduire une carte \u00e0 puce (carte d&rsquo;assurance maladie) pour les ouvrir<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h3>Les r\u00e9sultats<\/h3>\n<ul>\n<li>La collecte s\u00e9lective a atteint une moyenne de 81\u00a0%. La commune de Vallio Terme, pionni\u00e8re de l&rsquo;ensemble du projet, a atteint 93\u00a0% de collecte s\u00e9lective<\/li>\n<li>Une nette am\u00e9lioration de la partie des emballages plastiques et m\u00e9talliques a \u00e9t\u00e9 enregistr\u00e9e, avec une non-conformit\u00e9 de 7\u00a0%<\/li>\n<\/ul>\n","protected":false},"featured_media":2954,"parent":0,"template":"","class_list":["post-3463","referenze","type-referenze","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La collective s\u00e9lective: l&#039;objectif commun de cette vall\u00e9e | Sartori Ambiente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sartori-ambiente.com\/fr\/references\/la-collective-selective-lobjectif-commun-de-cette-vallee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La collective s\u00e9lective: l&#039;objectif commun de cette vall\u00e9e | Sartori Ambiente\" \/>\n<meta property=\"og:description\" content=\"\u00c9tat initial Les chiffres de la collecte s\u00e9lective de 2017, publi\u00e9s par l&rsquo;Observatoire provincial des d\u00e9chets, avant que la fili\u00e8re ne soit confi\u00e9e \u00e0 la soci\u00e9t\u00e9 Sae sp\u00e9cialement fond\u00e9e par la communaut\u00e9 de montagne, indiquaient un taux de collecte s\u00e9lective des d\u00e9chets de 50\u00a0%. Les difficult\u00e9s de la population \u00e0 apprendre \u00e0 trier correctement tous [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sartori-ambiente.com\/fr\/references\/la-collective-selective-lobjectif-commun-de-cette-vallee\/\" \/>\n<meta property=\"og:site_name\" content=\"Sartori Ambiente\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-18T16:40:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sartori-ambiente.com\/wp-content\/uploads\/2021\/10\/Senza-titolo-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"690\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sartori-ambiente.com\\\/fr\\\/references\\\/la-collective-selective-lobjectif-commun-de-cette-vallee\\\/\",\"url\":\"https:\\\/\\\/sartori-ambiente.com\\\/fr\\\/references\\\/la-collective-selective-lobjectif-commun-de-cette-vallee\\\/\",\"name\":\"La collective s\u00e9lective: l'objectif commun de cette vall\u00e9e | Sartori Ambiente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sartori-ambiente.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sartori-ambiente.com\\\/fr\\\/references\\\/la-collective-selective-lobjectif-commun-de-cette-vallee\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sartori-ambiente.com\\\/fr\\\/references\\\/la-collective-selective-lobjectif-commun-de-cette-vallee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sartori-ambiente.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Val-Sabbia-1.png\",\"datePublished\":\"2021-10-12T15:58:41+00:00\",\"dateModified\":\"2021-11-18T16:40:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sartori-ambiente.com\\\/fr\\\/references\\\/la-collective-selective-lobjectif-commun-de-cette-vallee\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sartori-ambiente.com\\\/fr\\\/references\\\/la-collective-selective-lobjectif-commun-de-cette-vallee\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sartori-ambiente.com\\\/fr\\\/references\\\/la-collective-selective-lobjectif-commun-de-cette-vallee\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sartori-ambiente.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Val-Sabbia-1.png\",\"contentUrl\":\"https:\\\/\\\/sartori-ambiente.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Val-Sabbia-1.png\",\"width\":700,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sartori-ambiente.com\\\/fr\\\/references\\\/la-collective-selective-lobjectif-commun-de-cette-vallee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Les r\u00e9f\u00e9rences\",\"item\":\"https:\\\/\\\/sartori-ambiente.com\\\/fr\\\/references\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La collective s\u00e9lective: l&#8217;objectif commun de cette vall\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sartori-ambiente.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/sartori-ambiente.com\\\/fr\\\/\",\"name\":\"Sartori Ambiente\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/sartori-ambiente.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sartori-ambiente.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sartori-ambiente.com\\\/fr\\\/#organization\",\"name\":\"Sartori Ambiente\",\"url\":\"https:\\\/\\\/sartori-ambiente.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sartori-ambiente.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sartori-ambiente.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Sartori_Ambiente_logo.svg\",\"contentUrl\":\"https:\\\/\\\/sartori-ambiente.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Sartori_Ambiente_logo.svg\",\"width\":1,\"height\":1,\"caption\":\"Sartori Ambiente\"},\"image\":{\"@id\":\"https:\\\/\\\/sartori-ambiente.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La collective s\u00e9lective: l'objectif commun de cette vall\u00e9e | Sartori Ambiente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sartori-ambiente.com\/fr\/references\/la-collective-selective-lobjectif-commun-de-cette-vallee\/","og_locale":"fr_FR","og_type":"article","og_title":"La collective s\u00e9lective: l'objectif commun de cette vall\u00e9e | Sartori Ambiente","og_description":"\u00c9tat initial Les chiffres de la collecte s\u00e9lective de 2017, publi\u00e9s par l&rsquo;Observatoire provincial des d\u00e9chets, avant que la fili\u00e8re ne soit confi\u00e9e \u00e0 la soci\u00e9t\u00e9 Sae sp\u00e9cialement fond\u00e9e par la communaut\u00e9 de montagne, indiquaient un taux de collecte s\u00e9lective des d\u00e9chets de 50\u00a0%. Les difficult\u00e9s de la population \u00e0 apprendre \u00e0 trier correctement tous [&hellip;]","og_url":"https:\/\/sartori-ambiente.com\/fr\/references\/la-collective-selective-lobjectif-commun-de-cette-vallee\/","og_site_name":"Sartori Ambiente","article_modified_time":"2021-11-18T16:40:37+00:00","og_image":[{"width":690,"height":600,"url":"https:\/\/sartori-ambiente.com\/wp-content\/uploads\/2021\/10\/Senza-titolo-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sartori-ambiente.com\/fr\/references\/la-collective-selective-lobjectif-commun-de-cette-vallee\/","url":"https:\/\/sartori-ambiente.com\/fr\/references\/la-collective-selective-lobjectif-commun-de-cette-vallee\/","name":"La collective s\u00e9lective: l'objectif commun de cette vall\u00e9e | Sartori Ambiente","isPartOf":{"@id":"https:\/\/sartori-ambiente.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sartori-ambiente.com\/fr\/references\/la-collective-selective-lobjectif-commun-de-cette-vallee\/#primaryimage"},"image":{"@id":"https:\/\/sartori-ambiente.com\/fr\/references\/la-collective-selective-lobjectif-commun-de-cette-vallee\/#primaryimage"},"thumbnailUrl":"https:\/\/sartori-ambiente.com\/wp-content\/uploads\/2021\/10\/Val-Sabbia-1.png","datePublished":"2021-10-12T15:58:41+00:00","dateModified":"2021-11-18T16:40:37+00:00","breadcrumb":{"@id":"https:\/\/sartori-ambiente.com\/fr\/references\/la-collective-selective-lobjectif-commun-de-cette-vallee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sartori-ambiente.com\/fr\/references\/la-collective-selective-lobjectif-commun-de-cette-vallee\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sartori-ambiente.com\/fr\/references\/la-collective-selective-lobjectif-commun-de-cette-vallee\/#primaryimage","url":"https:\/\/sartori-ambiente.com\/wp-content\/uploads\/2021\/10\/Val-Sabbia-1.png","contentUrl":"https:\/\/sartori-ambiente.com\/wp-content\/uploads\/2021\/10\/Val-Sabbia-1.png","width":700,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/sartori-ambiente.com\/fr\/references\/la-collective-selective-lobjectif-commun-de-cette-vallee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Les r\u00e9f\u00e9rences","item":"https:\/\/sartori-ambiente.com\/fr\/references\/"},{"@type":"ListItem","position":2,"name":"La collective s\u00e9lective: l&#8217;objectif commun de cette vall\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/sartori-ambiente.com\/fr\/#website","url":"https:\/\/sartori-ambiente.com\/fr\/","name":"Sartori Ambiente","description":"","publisher":{"@id":"https:\/\/sartori-ambiente.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sartori-ambiente.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/sartori-ambiente.com\/fr\/#organization","name":"Sartori Ambiente","url":"https:\/\/sartori-ambiente.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sartori-ambiente.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/sartori-ambiente.com\/wp-content\/uploads\/2021\/09\/Sartori_Ambiente_logo.svg","contentUrl":"https:\/\/sartori-ambiente.com\/wp-content\/uploads\/2021\/09\/Sartori_Ambiente_logo.svg","width":1,"height":1,"caption":"Sartori Ambiente"},"image":{"@id":"https:\/\/sartori-ambiente.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/sartori-ambiente.com\/fr\/wp-json\/wp\/v2\/referenze\/3463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sartori-ambiente.com\/fr\/wp-json\/wp\/v2\/referenze"}],"about":[{"href":"https:\/\/sartori-ambiente.com\/fr\/wp-json\/wp\/v2\/types\/referenze"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sartori-ambiente.com\/fr\/wp-json\/wp\/v2\/media\/2954"}],"wp:attachment":[{"href":"https:\/\/sartori-ambiente.com\/fr\/wp-json\/wp\/v2\/media?parent=3463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}